{
    "id": 15080,
    "date": "2025-07-31T14:28:40",
    "date_gmt": "2025-07-31T19:28:40",
    "guid": {
        "rendered": "https:\/\/certione.org\/product\/data-storytelling-professional-dsp\/"
    },
    "modified": "2026-02-26T18:25:21",
    "modified_gmt": "2026-02-26T23:25:21",
    "slug": "data-storytelling-professional-dsp",
    "status": "publish",
    "type": "product",
    "link": "https:\/\/www.certione.org\/pt\/produto\/data-storytelling-professional-dsp\/",
    "title": {
        "rendered": "Data Storytelling Professional (DSP)"
    },
    "content": {
        "rendered": "<p>O <strong>Data Storytelling Professional (DSP)<\/strong> A certifica\u00e7\u00e3o foi criada para ensinar como transformar dados em narrativas que geram impacto real. Embora os analistas e os cientistas de dados descubram insights valiosos, muitas vezes eles n\u00e3o conseguem gerar a\u00e7\u00f5es devido a uma lacuna na comunica\u00e7\u00e3o com os tomadores de decis\u00e3o. Este curso preenche essa lacuna usando a narra\u00e7\u00e3o de hist\u00f3rias como o elo entre os dados e as decis\u00f5es, combinando l\u00f3gica, emo\u00e7\u00e3o e visualiza\u00e7\u00e3o para inspirar mudan\u00e7as.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>A certifica\u00e7\u00e3o Data Storytelling Professional (DSP) foi criada para ensinar como transformar dados em narrativas que geram impacto real. Embora os analistas e cientistas de dados descubram insights valiosos, muitas vezes eles n\u00e3o conseguem gerar a\u00e7\u00f5es devido a uma falha de comunica\u00e7\u00e3o com...<\/p>",
        "protected": false
    },
    "featured_media": 15106,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "_acf_changed": false
    },
    "product_brand": [],
    "product_cat": [
        302
    ],
    "product_tag": [],
    "class_list": {
        "0": "post-15080",
        "1": "product",
        "2": "type-product",
        "3": "status-publish",
        "4": "has-post-thumbnail",
        "6": "product_cat-big-data",
        "8": "first",
        "9": "instock",
        "10": "sold-individually",
        "11": "shipping-taxable",
        "12": "purchasable",
        "13": "product-type-variable"
    },
    "acf": [],
    "_links": {
        "self": [
            {
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/product\/15080",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/product"
            }
        ],
        "about": [
            {
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/types\/product"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/comments?post=15080"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/media\/15106"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/media?parent=15080"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "product_brand",
                "embeddable": true,
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/product_brand?post=15080"
            },
            {
                "taxonomy": "product_cat",
                "embeddable": true,
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/product_cat?post=15080"
            },
            {
                "taxonomy": "product_tag",
                "embeddable": true,
                "href": "https:\/\/www.certione.org\/pt\/wp-json\/wp\/v2\/product_tag?post=15080"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}